{"id":517,"date":"2022-03-19T10:12:34","date_gmt":"2022-03-19T09:12:34","guid":{"rendered":"https:\/\/www.uni-weimar.de\/projekte\/spectra\/?p=517"},"modified":"2026-05-27T17:18:09","modified_gmt":"2026-05-27T15:18:09","slug":"ausstellung-altes-sanatorium-schwarzeck","status":"publish","type":"post","link":"https:\/\/www.uni-weimar.de\/projekte\/spectra\/ausstellung-altes-sanatorium-schwarzeck\/","title":{"rendered":"Altes Sanatorium Schwarzeck"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":516,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_crdt_document":""},"categories":[62,14,69],"tags":[85,121],"personen":[],"class_list":["post-517","post","type-post","status-publish","has-post-thumbnail","hentry","category-interaktives","category-kulturelle-bildung-im-laendlichen-raum","category-lernraum-bauhaus","tag-installation","tag-performance"],"acf":[],"grid":"{\"colCount\":12,\"colGutter\":1,\"rowGutters\":[5,2,2,5,2,2,5,5],\"frameMargin\":5,\"leftFrameMargin\":5,\"rightFrameMargin\":5,\"topFrameMargin\":40,\"mus\":{\"colGutterMu\":\"%\",\"rowGutterMu\":\"%\",\"topFrameMu\":\"px\",\"bottomFrameMu\":\"%\",\"frameMu\":\"%\"},\"bottomFrameMargin\":5,\"rowAttrs\":[{\"relid\":5},{\"relid\":23},{\"relid\":3},{\"relid\":21,\"classes\":\"container-project-meta\"},{\"relid\":25},{\"relid\":1},{\"relid\":22},{\"relid\":9},{\"relid\":8}],\"bgColor\":null,\"bgImage\":null,\"cont\":[{\"type\":\"shortcode\",\"cont\":\"[project_title]\",\"align\":\"middle\",\"row\":0,\"col\":0,\"colspan\":6,\"offsetx\":0,\"offsety\":0,\"spaceabove\":0,\"spacebelow\":0,\"yvel\":1,\"push\":0,\"relid\":6,\"shortcodeid\":1770304048121,\"absolute_position\":false},{\"type\":\"shortcode\",\"cont\":\"[acf_textfield name=\\\"projekt_zeitraum\\\" label=\\\"Jahr:\\\"]\",\"align\":\"top\",\"row\":1,\"col\":0,\"colspan\":1,\"offsetx\":0,\"offsety\":0,\"spaceabove\":0,\"spacebelow\":0,\"yvel\":1,\"push\":0,\"relid\":14,\"shortcodeid\":1773309373352,\"absolute_position\":false},{\"type\":\"shortcode\",\"cont\":\"[acf_textfield name=\\\"projekt_personen\\\" label=\\\"Personen:\\\"]\",\"align\":\"top\",\"row\":1,\"col\":6,\"colspan\":4,\"offsetx\":0,\"offsety\":0,\"spaceabove\":0,\"spacebelow\":0,\"yvel\":1,\"push\":5,\"relid\":12,\"shortcodeid\":1773407360029,\"absolute_position\":false,\"frameOverflow\":\"\"},{\"type\":\"img\",\"cont\":\"\/wp-content\/uploads\/2026\/03\/Schwarzeck_Ausstellungen-8.jpg\",\"align\":\"top\",\"row\":2,\"col\":3,\"colspan\":2,\"offsetx\":0,\"offsety\":0,\"spaceabove\":0,\"spacebelow\":0,\"yvel\":1,\"push\":3,\"relid\":4,\"attid\":515,\"sizes\":{\"full\":\"\/wp-content\/uploads\/2026\/03\/Schwarzeck_Ausstellungen-8.jpg\",\"_1024\":\"\/wp-content\/uploads\/2026\/03\/Schwarzeck_Ausstellungen-8-1024x1365.jpg\",\"_768\":\"\/wp-content\/uploads\/2026\/03\/Schwarzeck_Ausstellungen-8-768x1024.jpg\",\"_512\":\"\/wp-content\/uploads\/2026\/03\/Schwarzeck_Ausstellungen-8-512x683.jpg\",\"_265\":\"\/wp-content\/uploads\/2026\/03\/Schwarzeck_Ausstellungen-8-265x353.jpg\"},\"w\":1200,\"h\":1600,\"ar\":1.3333333333333333,\"alt\":\"Ausstellung Altes Sanatorium Schwarzeck. Tisch mit Fotos\",\"absolute_position\":false,\"textOnElement\":{\"topLeft\":\"\",\"topCenter\":\"\",\"topRight\":\"\",\"leftCenter\":\"\",\"centerCenter\":\"\",\"rightCenter\":\"\",\"bottomLeft\":\"\",\"bottomCenter\":\"\",\"bottomRight\":\"\",\"spaceLeftRight\":10,\"spaceLeftRightMu\":\"px\",\"spaceTopBottom\":10,\"spaceTopBottomMu\":\"px\",\"enableSpacePhone\":false,\"spaceLeftRightPhone\":10,\"spaceLeftRightPhoneMu\":\"px\",\"spaceTopBottomPhone\":10,\"spaceTopBottomPhoneMu\":\"px\",\"verticalOffsetCenter\":0,\"verticalOffsetCenterMu\":\"px\",\"verticalOffsetCenterPhone\":0,\"verticalOffsetCenterPhoneMu\":\"px\",\"darkGradientAtTop\":false,\"darkGradientAtBottom\":false,\"darkGradientAtTopColor\":\"#000000\",\"darkGradientAtBottomColor\":\"#000000\"},\"frameOverflow\":\"\"},{\"type\":\"img\",\"cont\":\"\/wp-content\/uploads\/2026\/03\/Schwarzeck_Ausstellungen-9.jpg\",\"align\":\"top\",\"row\":2,\"col\":5,\"colspan\":2,\"offsetx\":0,\"offsety\":0,\"spaceabove\":0,\"spacebelow\":0,\"yvel\":1,\"push\":0,\"relid\":10,\"attid\":516,\"sizes\":{\"full\":\"\/wp-content\/uploads\/2026\/03\/Schwarzeck_Ausstellungen-9.jpg\",\"_1024\":\"\/wp-content\/uploads\/2026\/03\/Schwarzeck_Ausstellungen-9-1024x1365.jpg\",\"_768\":\"\/wp-content\/uploads\/2026\/03\/Schwarzeck_Ausstellungen-9-768x1024.jpg\",\"_512\":\"\/wp-content\/uploads\/2026\/03\/Schwarzeck_Ausstellungen-9-512x683.jpg\",\"_265\":\"\/wp-content\/uploads\/2026\/03\/Schwarzeck_Ausstellungen-9-265x353.jpg\"},\"w\":1200,\"h\":1600,\"ar\":1.3333333333333333,\"alt\":\"Ausstellung Altes Sanatorium Schwarzeck. Besucher\",\"absolute_position\":false},{\"type\":\"img\",\"cont\":\"\/wp-content\/uploads\/2026\/03\/Schwarzeck_Ausstellungen-6.jpg\",\"align\":\"top\",\"row\":2,\"col\":7,\"colspan\":2,\"offsetx\":0,\"offsety\":0,\"spaceabove\":0,\"spacebelow\":0,\"yvel\":1,\"push\":0,\"relid\":13,\"attid\":514,\"sizes\":{\"full\":\"\/wp-content\/uploads\/2026\/03\/Schwarzeck_Ausstellungen-6.jpg\",\"_1024\":\"\/wp-content\/uploads\/2026\/03\/Schwarzeck_Ausstellungen-6-1024x1365.jpg\",\"_768\":\"\/wp-content\/uploads\/2026\/03\/Schwarzeck_Ausstellungen-6-768x1024.jpg\",\"_512\":\"\/wp-content\/uploads\/2026\/03\/Schwarzeck_Ausstellungen-6-512x683.jpg\",\"_265\":\"\/wp-content\/uploads\/2026\/03\/Schwarzeck_Ausstellungen-6-265x353.jpg\"},\"w\":1200,\"h\":1600,\"ar\":1.3333333333333333,\"alt\":\"Ausstellung Altes Sanatorium Schwarzeck. Gespr\\u00e4ch\",\"absolute_position\":false,\"textOnElement\":{\"topLeft\":\"\",\"topCenter\":\"\",\"topRight\":\"\",\"leftCenter\":\"\",\"centerCenter\":\"\",\"rightCenter\":\"\",\"bottomLeft\":\"\",\"bottomCenter\":\"\",\"bottomRight\":\"\",\"spaceLeftRight\":10,\"spaceLeftRightMu\":\"px\",\"spaceTopBottom\":10,\"spaceTopBottomMu\":\"px\",\"enableSpacePhone\":false,\"spaceLeftRightPhone\":10,\"spaceLeftRightPhoneMu\":\"px\",\"spaceTopBottomPhone\":10,\"spaceTopBottomPhoneMu\":\"px\",\"verticalOffsetCenter\":0,\"verticalOffsetCenterMu\":\"px\",\"verticalOffsetCenterPhone\":0,\"verticalOffsetCenterPhoneMu\":\"px\",\"darkGradientAtTop\":false,\"darkGradientAtBottom\":false,\"darkGradientAtTopColor\":\"#000000\",\"darkGradientAtBottomColor\":\"#000000\"}},{\"type\":\"shortcode\",\"cont\":\"[project_info parent=\\\"themen\\\"]\",\"align\":\"top\",\"row\":3,\"col\":3,\"colspan\":3,\"offsetx\":0,\"offsety\":0,\"spaceabove\":0,\"spacebelow\":0,\"yvel\":1,\"push\":3,\"relid\":16,\"shortcodeid\":1770740252647,\"absolute_position\":false,\"frameOverflow\":\"\"},{\"type\":\"shortcode\",\"cont\":\"[project_info parent=\\\"typ\\\"]\",\"align\":\"top\",\"row\":3,\"col\":6,\"colspan\":3,\"offsetx\":0,\"offsety\":0,\"spaceabove\":0,\"spacebelow\":0,\"yvel\":1,\"push\":0,\"relid\":17,\"shortcodeid\":1770298592188,\"absolute_position\":false,\"frameOverflow\":\"\"},{\"type\":\"shortcode\",\"cont\":\"[show_tags]\",\"align\":\"top\",\"row\":3,\"col\":9,\"colspan\":2,\"offsetx\":0,\"offsety\":0,\"spaceabove\":0,\"spacebelow\":0,\"yvel\":1,\"push\":0,\"relid\":20,\"shortcodeid\":1770300546712,\"absolute_position\":false},{\"type\":\"hr\",\"cont\":\"\",\"align\":\"middle\",\"row\":4,\"col\":0,\"colspan\":12,\"offsetx\":0,\"offsety\":0,\"spaceabove\":0,\"spacebelow\":0,\"yvel\":1,\"push\":0,\"relid\":26,\"absolute_position\":false,\"frameOverflow\":\"\"},{\"type\":\"text\",\"cont\":\"<p>Im Rahmen des Fachmoduls \\\"LandKulturBildung. Altes Sanatorium Schwarzeck\\\" erforschten Studierende der Fakult\\u00e4t Kunst und Gestaltung das 1901 am s\\u00fcdlichen Rande des Luftkurortes Bad Blankenburg gegr\\u00fcndete \\\"Th\\u00fcringer Waldsanatorium Schwarzeck\\\". Auf dem neusten Stand der Wissenschaft entstand eine Heilanstalt, welche die Kleinstadt im Th\\u00fcringer Wald einst weit \\u00fcber die Grenzen Th\\u00fcringens hinaus bekannt machte. Doch ihre Bedeutung f\\u00fcr das Leben in der l\\u00e4ndlich gepr\\u00e4gten Region ist in die Jahre gekommen. Als Luftwaffenschule der NS-Zeit und als Parteischule der DDR wurde Schwarzeck zu einem schwarzen Fleck in der Landkarte und blieb der \\u00d6ffentlichkeit vorbehalten. Stattdessen wurde es f\\u00fcr die \\u00f6rtliche Bev\\u00f6lkerung zu einem Palast des Unbekannten, einer Projektion aus\\u00a0Spekulationen und Vorurteilen. Heute kann das Schwarzeck seine 20 Jahre Leerstand nicht mehr leugnen, Diebstahl, Brandstiftung und Verfalls verformen seine Vergangenheit zu einem ausweglosen Labyrinth und die emporwachsende Flora und Fauna verdeckt nach Erinnerung schreiende Spuren.<\/p><p>Innerhalb einer intensiven k\\u00fcnstlerisch(-forschenden) Auseinandersetzung mit der Vergangenheit und Gegenwart des Sanatoriums entwickelten 16 Studierende installative, performative und intervenierende k\\u00fcnstlerische Positionen, welche zum einen zur summaery 2022, zum anderen im Rahmen des Tages der Sommerfrische 2022 im Sanatorium selbst zu sehen waren.<\/p><p>Herzlichen Dank gilt Gunter Bank, Markus K\\u00fchn und Wolfgang K\\u00fcnzel des\\u00a0 Vereins Schwarzeckfreunde Bad Blankenburg e.V. f\\u00fcr ihre tatkr\\u00e4ftige und unerm\\u00fcdliche Unterst\\u00fctzung unserer Recherchen, das Teilen ihres Wissen, das Erm\\u00f6glichen aller Aufenthalte im Haus sowie die liebe Gastfreundschaft, die uns entgegengebracht wurde. Zudem gilt unser Dank der Initiative Zukunftswerkstatt Schwarzatale e.V., insbesondere Burkhardt Kolbm\\u00fcller, f\\u00fcr die M\\u00f6glichkeit im Rahmen des Tages der Sommerfrische 2022 im Sanatorium auszustellen.<\/p>\",\"align\":\"top\",\"row\":5,\"col\":3,\"colspan\":6,\"offsetx\":0,\"offsety\":0,\"spaceabove\":0,\"spacebelow\":0,\"yvel\":1,\"push\":3,\"relid\":2,\"absolute_position\":false,\"zIndex\":0},{\"type\":\"shortcode\",\"cont\":\"[acf_textfield name=\\\"projekt_betreuung\\\" label=\\\"Betreuung:\\\"]\",\"align\":\"top\",\"row\":6,\"col\":3,\"colspan\":6,\"offsetx\":0,\"offsety\":0,\"spaceabove\":0,\"spacebelow\":0,\"yvel\":1,\"push\":3,\"relid\":19,\"shortcodeid\":1770636231007,\"absolute_position\":false,\"frameOverflow\":\"\"},{\"type\":\"img\",\"cont\":\"\/wp-content\/uploads\/2026\/03\/Schwarzeck_Ausstellungen-1.jpg\",\"align\":\"top\",\"row\":7,\"col\":2,\"colspan\":2,\"offsetx\":0,\"offsety\":0,\"spaceabove\":0,\"spacebelow\":0,\"yvel\":1,\"push\":2,\"relid\":7,\"attid\":511,\"sizes\":{\"full\":\"\/wp-content\/uploads\/2026\/03\/Schwarzeck_Ausstellungen-1.jpg\",\"_1024\":\"\/wp-content\/uploads\/2026\/03\/Schwarzeck_Ausstellungen-1-1024x1365.jpg\",\"_768\":\"\/wp-content\/uploads\/2026\/03\/Schwarzeck_Ausstellungen-1-768x1024.jpg\",\"_512\":\"\/wp-content\/uploads\/2026\/03\/Schwarzeck_Ausstellungen-1-512x683.jpg\",\"_265\":\"\/wp-content\/uploads\/2026\/03\/Schwarzeck_Ausstellungen-1-265x353.jpg\"},\"w\":1200,\"h\":1600,\"ar\":1.3333333333333333,\"alt\":\"Ausstellung Altes Sanatorium Schwarzeck\",\"absolute_position\":false},{\"type\":\"img\",\"cont\":\"\/wp-content\/uploads\/2026\/03\/Schwarzeck_Ausstellungen-5.jpg\",\"align\":\"top\",\"row\":7,\"col\":4,\"colspan\":4,\"offsetx\":0,\"offsety\":0,\"spaceabove\":0,\"spacebelow\":0,\"yvel\":1,\"push\":0,\"relid\":11,\"attid\":513,\"sizes\":{\"full\":\"\/wp-content\/uploads\/2026\/03\/Schwarzeck_Ausstellungen-5.jpg\",\"_1280\":\"\/wp-content\/uploads\/2026\/03\/Schwarzeck_Ausstellungen-5-1280x960.jpg\",\"_1024\":\"\/wp-content\/uploads\/2026\/03\/Schwarzeck_Ausstellungen-5-1024x768.jpg\",\"_768\":\"\/wp-content\/uploads\/2026\/03\/Schwarzeck_Ausstellungen-5-768x576.jpg\",\"_512\":\"\/wp-content\/uploads\/2026\/03\/Schwarzeck_Ausstellungen-5-512x384.jpg\",\"_265\":\"\/wp-content\/uploads\/2026\/03\/Schwarzeck_Ausstellungen-5-265x199.jpg\"},\"w\":1600,\"h\":1200,\"ar\":0.75,\"alt\":\"Ausstellung Altes Sanatorium Schwarzeck. Glas\",\"absolute_position\":false,\"textOnElement\":{\"topLeft\":\"\",\"topCenter\":\"\",\"topRight\":\"\",\"leftCenter\":\"\",\"centerCenter\":\"\",\"rightCenter\":\"\",\"bottomLeft\":\"\",\"bottomCenter\":\"\",\"bottomRight\":\"\",\"spaceLeftRight\":10,\"spaceLeftRightMu\":\"px\",\"spaceTopBottom\":10,\"spaceTopBottomMu\":\"px\",\"enableSpacePhone\":false,\"spaceLeftRightPhone\":10,\"spaceLeftRightPhoneMu\":\"px\",\"spaceTopBottomPhone\":10,\"spaceTopBottomPhoneMu\":\"px\",\"verticalOffsetCenter\":0,\"verticalOffsetCenterMu\":\"px\",\"verticalOffsetCenterPhone\":0,\"verticalOffsetCenterPhoneMu\":\"px\",\"darkGradientAtTop\":false,\"darkGradientAtBottom\":false,\"darkGradientAtTopColor\":\"#000000\",\"darkGradientAtBottomColor\":\"#000000\"},\"frameOverflow\":\"\"},{\"type\":\"img\",\"cont\":\"\/wp-content\/uploads\/2026\/03\/Schwarzeck_Ausstellungen-4.jpg\",\"align\":\"top\",\"row\":7,\"col\":8,\"colspan\":2,\"offsetx\":0,\"offsety\":0,\"spaceabove\":0,\"spacebelow\":0,\"yvel\":1,\"push\":0,\"relid\":15,\"attid\":512,\"sizes\":{\"full\":\"\/wp-content\/uploads\/2026\/03\/Schwarzeck_Ausstellungen-4.jpg\",\"_1024\":\"\/wp-content\/uploads\/2026\/03\/Schwarzeck_Ausstellungen-4-1024x1365.jpg\",\"_768\":\"\/wp-content\/uploads\/2026\/03\/Schwarzeck_Ausstellungen-4-768x1024.jpg\",\"_512\":\"\/wp-content\/uploads\/2026\/03\/Schwarzeck_Ausstellungen-4-512x683.jpg\",\"_265\":\"\/wp-content\/uploads\/2026\/03\/Schwarzeck_Ausstellungen-4-265x353.jpg\"},\"w\":1200,\"h\":1600,\"ar\":1.3333333333333333,\"alt\":\"Ausstellung Altes Sanatorium Schwarzeck. Audioinstallation\",\"absolute_position\":false},{\"type\":\"shortcode\",\"cont\":\"[project_info parent=\\\"projekt-foerderer\\\"]\",\"align\":\"top\",\"row\":8,\"col\":3,\"colspan\":6,\"offsetx\":0,\"offsety\":0,\"spaceabove\":0,\"spacebelow\":0,\"yvel\":1,\"push\":3,\"relid\":18,\"shortcodeid\":1773842161867,\"absolute_position\":false,\"frameOverflow\":\"\"}]}","phonegrid":"{\"colCount\":12,\"colGutter\":1,\"rowGutters\":[5,5,5,5,5,5,5,5,5,5,5,5],\"frameMargin\":5,\"leftFrameMargin\":5,\"rightFrameMargin\":5,\"topFrameMargin\":5,\"mus\":{\"colGutterMu\":\"%\",\"rowGutterMu\":\"%\",\"topFrameMu\":\"%\",\"bottomFrameMu\":\"%\",\"frameMu\":\"%\"},\"bottomFrameMargin\":5,\"rowAttrs\":[{\"relid\":37},{\"relid\":38},{\"relid\":39},{\"relid\":40},{\"relid\":41},{\"relid\":42},{\"relid\":43},{\"relid\":44},{\"relid\":45},{\"relid\":46},{\"relid\":47},{\"relid\":48},{\"relid\":49}],\"bgColor\":null,\"bgImage\":null,\"cont\":[{\"type\":\"shortcode\",\"cont\":\"[project_title]\",\"align\":\"bottom\",\"row\":0,\"col\":0,\"colspan\":12,\"offsetx\":0,\"offsety\":0,\"spaceabove\":0,\"spacebelow\":0,\"yvel\":1,\"push\":0,\"relid\":6,\"shortcodeid\":1770304048121,\"absolute_position\":false},{\"type\":\"shortcode\",\"cont\":\"[acf_textfield name=\\\"projekt_zeitraum\\\" label=\\\"Jahr:\\\"]\",\"align\":\"bottom\",\"row\":1,\"col\":0,\"colspan\":12,\"offsetx\":0,\"offsety\":0,\"spaceabove\":0,\"spacebelow\":0,\"yvel\":1,\"push\":0,\"relid\":14,\"shortcodeid\":1773407678730,\"absolute_position\":false},{\"type\":\"shortcode\",\"cont\":\"[acf_textfield name=\\\"projekt_personen\\\" label=\\\"Personen:\\\"]\",\"align\":\"bottom\",\"row\":2,\"col\":0,\"colspan\":12,\"offsetx\":0,\"offsety\":0,\"spaceabove\":0,\"spacebelow\":0,\"yvel\":1,\"push\":0,\"relid\":36,\"shortcodeid\":1773407695634,\"absolute_position\":false},{\"type\":\"img\",\"cont\":\"\/wp-content\/uploads\/2026\/03\/Schwarzeck_Ausstellungen-5.jpg\",\"align\":\"bottom\",\"row\":3,\"col\":0,\"colspan\":12,\"offsetx\":0,\"offsety\":0,\"spaceabove\":0,\"spacebelow\":0,\"yvel\":1,\"push\":0,\"relid\":11,\"attid\":513,\"sizes\":{\"full\":\"\/wp-content\/uploads\/2026\/03\/Schwarzeck_Ausstellungen-5.jpg\",\"_1280\":\"\/wp-content\/uploads\/2026\/03\/Schwarzeck_Ausstellungen-5-1280x960.jpg\",\"_1024\":\"\/wp-content\/uploads\/2026\/03\/Schwarzeck_Ausstellungen-5-1024x768.jpg\",\"_768\":\"\/wp-content\/uploads\/2026\/03\/Schwarzeck_Ausstellungen-5-768x576.jpg\",\"_512\":\"\/wp-content\/uploads\/2026\/03\/Schwarzeck_Ausstellungen-5-512x384.jpg\",\"_265\":\"\/wp-content\/uploads\/2026\/03\/Schwarzeck_Ausstellungen-5-265x199.jpg\"},\"w\":1600,\"h\":1200,\"ar\":0.75,\"alt\":\"Ausstellung Altes Sanatorium Schwarzeck. Glas\",\"absolute_position\":false,\"textOnElement\":{\"topLeft\":\"\",\"topCenter\":\"\",\"topRight\":\"\",\"leftCenter\":\"\",\"centerCenter\":\"\",\"rightCenter\":\"\",\"bottomLeft\":\"\",\"bottomCenter\":\"\",\"bottomRight\":\"\",\"spaceLeftRight\":10,\"spaceLeftRightMu\":\"px\",\"spaceTopBottom\":10,\"spaceTopBottomMu\":\"px\",\"enableSpacePhone\":false,\"spaceLeftRightPhone\":10,\"spaceLeftRightPhoneMu\":\"px\",\"spaceTopBottomPhone\":10,\"spaceTopBottomPhoneMu\":\"px\",\"verticalOffsetCenter\":0,\"verticalOffsetCenterMu\":\"px\",\"verticalOffsetCenterPhone\":0,\"verticalOffsetCenterPhoneMu\":\"px\",\"darkGradientAtTop\":false,\"darkGradientAtBottom\":false,\"darkGradientAtTopColor\":\"#000000\",\"darkGradientAtBottomColor\":\"#000000\"}},{\"type\":\"shortcode\",\"cont\":\"[project_info parent=\\\"themen\\\"]\",\"align\":\"bottom\",\"row\":4,\"col\":0,\"colspan\":12,\"offsetx\":0,\"offsety\":0,\"spaceabove\":0,\"spacebelow\":0,\"yvel\":1,\"push\":0,\"relid\":16,\"shortcodeid\":1770740252647,\"absolute_position\":false},{\"type\":\"shortcode\",\"cont\":\"[project_info parent=\\\"typ\\\"]\",\"align\":\"bottom\",\"row\":5,\"col\":0,\"colspan\":12,\"offsetx\":0,\"offsety\":0,\"spaceabove\":0,\"spacebelow\":0,\"yvel\":1,\"push\":0,\"relid\":17,\"shortcodeid\":1770298592188,\"absolute_position\":false},{\"type\":\"shortcode\",\"cont\":\"[project_info parent=\\\"projekt-foerderer\\\"]\",\"align\":\"bottom\",\"row\":6,\"col\":0,\"colspan\":12,\"offsetx\":0,\"offsety\":0,\"spaceabove\":0,\"spacebelow\":0,\"yvel\":1,\"push\":0,\"relid\":18,\"shortcodeid\":1773842161867,\"absolute_position\":false},{\"type\":\"shortcode\",\"cont\":\"[acf_textfield name=\\\"projekt_betreuung\\\" label=\\\"Betreuung:\\\"]\",\"align\":\"bottom\",\"row\":7,\"col\":0,\"colspan\":12,\"offsetx\":0,\"offsety\":0,\"spaceabove\":0,\"spacebelow\":0,\"yvel\":1,\"push\":0,\"relid\":19,\"shortcodeid\":1770636231007,\"absolute_position\":false},{\"type\":\"shortcode\",\"cont\":\"[show_tags]\",\"align\":\"bottom\",\"row\":8,\"col\":0,\"colspan\":12,\"offsetx\":0,\"offsety\":0,\"spaceabove\":0,\"spacebelow\":0,\"yvel\":1,\"push\":0,\"relid\":20,\"shortcodeid\":1770300546712,\"absolute_position\":false},{\"type\":\"hr\",\"cont\":\"\",\"align\":\"bottom\",\"row\":9,\"col\":0,\"colspan\":12,\"offsetx\":0,\"offsety\":0,\"spaceabove\":0,\"spacebelow\":0,\"yvel\":1,\"push\":0,\"relid\":26,\"absolute_position\":false},{\"type\":\"text\",\"cont\":\"<p>Im Rahmen des Fachmoduls \\\"LandKulturBildung. Altes Sanatorium Schwarzeck\\\" erforschten Studierende der Fakult\\u00e4t Kunst und Gestaltung das 1901 am s\\u00fcdlichen Rande des Luftkurortes Bad Blankenburg gegr\\u00fcndete \\\"Th\\u00fcringer Waldsanatorium Schwarzeck\\\". Auf dem neusten Stand der Wissenschaft entstand eine Heilanstalt, welche die Kleinstadt im Th\\u00fcringer Wald einst weit \\u00fcber die Grenzen Th\\u00fcringens hinaus bekannt machte. Doch ihre Bedeutung f\\u00fcr das Leben in der l\\u00e4ndlich gepr\\u00e4gten Region ist in die Jahre gekommen. Als Luftwaffenschule der NS-Zeit und als Parteischule der DDR wurde Schwarzeck zu einem schwarzen Fleck in der Landkarte und blieb der \\u00d6ffentlichkeit vorbehalten. Stattdessen wurde es f\\u00fcr die \\u00f6rtliche Bev\\u00f6lkerung zu einem Palast des Unbekannten, einer Projektion aus\\u00a0Spekulationen und Vorurteilen. Heute kann das Schwarzeck seine 20 Jahre Leerstand nicht mehr leugnen, Diebstahl, Brandstiftung und Verfalls verformen seine Vergangenheit zu einem ausweglosen Labyrinth und die emporwachsende Flora und Fauna verdeckt nach Erinnerung schreiende Spuren.<\/p><p>Innerhalb einer intensiven k\\u00fcnstlerisch(-forschenden) Auseinandersetzung mit der Vergangenheit und Gegenwart des Sanatoriums entwickelten 16 Studierende installative, performative und intervenierende k\\u00fcnstlerische Positionen, welche zum einen zur summaery 2022, zum anderen im Rahmen des Tages der Sommerfrische 2022 im Sanatorium selbst zu sehen waren.<\/p><p>Herzlichen Dank gilt Gunter Bank, Markus K\\u00fchn und Wolfgang K\\u00fcnzel des\\u00a0 Vereins Schwarzeckfreunde Bad Blankenburg e.V. f\\u00fcr ihre tatkr\\u00e4ftige und unerm\\u00fcdliche Unterst\\u00fctzung unserer Recherchen, das Teilen ihres Wissen, das Erm\\u00f6glichen aller Aufenthalte im Haus sowie die liebe Gastfreundschaft, die uns entgegengebracht wurde. Zudem gilt unser Dank der Initiative Zukunftswerkstatt Schwarzatale e.V., insbesondere Burkhardt Kolbm\\u00fcller, f\\u00fcr die M\\u00f6glichkeit im Rahmen des Tages der Sommerfrische 2022 im Sanatorium auszustellen.<\/p>\",\"align\":\"bottom\",\"row\":10,\"col\":0,\"colspan\":12,\"offsetx\":0,\"offsety\":0,\"spaceabove\":0,\"spacebelow\":0,\"yvel\":1,\"push\":0,\"relid\":2,\"absolute_position\":false,\"zIndex\":0}]}","_links":{"self":[{"href":"https:\/\/www.uni-weimar.de\/projekte\/spectra\/wp-json\/wp\/v2\/posts\/517","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.uni-weimar.de\/projekte\/spectra\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.uni-weimar.de\/projekte\/spectra\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.uni-weimar.de\/projekte\/spectra\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.uni-weimar.de\/projekte\/spectra\/wp-json\/wp\/v2\/comments?post=517"}],"version-history":[{"count":0,"href":"https:\/\/www.uni-weimar.de\/projekte\/spectra\/wp-json\/wp\/v2\/posts\/517\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.uni-weimar.de\/projekte\/spectra\/wp-json\/wp\/v2\/media\/516"}],"wp:attachment":[{"href":"https:\/\/www.uni-weimar.de\/projekte\/spectra\/wp-json\/wp\/v2\/media?parent=517"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.uni-weimar.de\/projekte\/spectra\/wp-json\/wp\/v2\/categories?post=517"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.uni-weimar.de\/projekte\/spectra\/wp-json\/wp\/v2\/tags?post=517"},{"taxonomy":"personen","embeddable":true,"href":"https:\/\/www.uni-weimar.de\/projekte\/spectra\/wp-json\/wp\/v2\/personen?post=517"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}